{"id":3973,"date":"2018-06-20T10:08:34","date_gmt":"2018-06-20T08:08:34","guid":{"rendered":"http:\/\/jamonappetit.com\/conditions-generales-de-vente\/"},"modified":"2018-06-20T10:08:34","modified_gmt":"2018-06-20T08:08:34","slug":"conditions-generales-de-vente","status":"publish","type":"page","link":"https:\/\/jamonappetit.com\/fr\/conditions-generales-de-vente\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales de vente"},"content":{"rendered":"<p><strong>Pr\u00e9ambule<\/strong><\/p>\n<p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente sont conclues entre Jamon Appetit et toute personne effectuant un achat en ligne via le site www.jamonappetit.com (ci-apr\u00e8s d\u00e9nomm\u00e9e \u00able client\u00a0\u00bb).<\/p>\n<p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente d\u00e9finissent\u00a0les modalit\u00e9s de vente entre \u00ab\u00a0Jam\u00f3n App\u00e9tit\u00a0\u00bb et \u00ab\u00a0le client\u00a0\u00bb de la commande \u00e0 la livraison.<\/p>\n<p>En validant sa commande, \u00ab\u00a0le client\u00a0\u00bb d\u00e9clare accepter sans r\u00e9serve les termes de la dite commande ainsi que l\u2019int\u00e9gralit\u00e9 des pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente.<\/p>\n<p><strong>Commandes<\/strong><\/p>\n<p><strong>Date de la commande<\/strong><\/p>\n<p>La date effective de la commande est celle de sa validation par le client suivie de la r\u00e9ception de l\u2019int\u00e9gralit\u00e9 du paiement effectu\u00e9 en ligne sur le site www.jamonappetit.com. Les d\u00e9lais de livraison indiqu\u00e9s sur le site prennent effet \u00e0 partir de cette date.<\/p>\n<p><strong>Caract\u00e9ristiques du produit<\/strong><\/p>\n<p>Les caract\u00e9ristiques des produits sont d\u00e9crites dans chaque fiche produit. Les photographies n\u2019entrent pas dans le champ contractuel. La responsabilit\u00e9 de la soci\u00e9t\u00e9 Jamon Appetit ne saurait \u00eatre engag\u00e9e en cas de diff\u00e9rence entre la photographie pr\u00e9sent\u00e9e et le produit re\u00e7u.<\/p>\n<p><strong>Prix<\/strong><\/p>\n<p>Les prix des produits sont indiqu\u00e9s en Euros, toutes taxes comprises et frais d\u2019exp\u00e9dition sont indiqu\u00e9s.<\/p>\n<p>Jamon Appetit se r\u00e9serve le droit de modifier ses prix \u00e0 tout moment. Les produits seront factur\u00e9s au tarif en vigueur au moment de l\u2019enregistrement de la commande.<\/p>\n<p><strong>Confirmation de commande<\/strong><\/p>\n<p>Un courrier \u00e9lectronique est automatiquement envoy\u00e9 au client afin de confirmer la prise de commande, et sous r\u00e9serve que l\u2019adresse \u00e9lectronique indiqu\u00e9e dans le formulaire de cr\u00e9ation de compte ne comporte pas d\u2019erreur.<\/p>\n<p>Jam\u00f3n App\u00e9tit n\u2019envoie pas de confirmation de commande par voie postale ni par t\u00e9l\u00e9phone.<\/p>\n<p><strong>Modalit\u00e9s de Paiement<\/strong><\/p>\n<p>Le paiement des articles command\u00e9s sur le site www.jamonappetit.com est payable en totalit\u00e9 \u00e0 la commande.<\/p>\n<p>Les moyens de paiement accept\u00e9s sont la carte bancaire, ainsi Stripe et Paypal.<\/p>\n<p>Le paiement en ligne de la commande est enti\u00e8rement s\u00e9curis\u00e9.<\/p>\n<p>Tous les moyens n\u00e9cessaires pour assurer la s\u00e9curit\u00e9 et la confidentialit\u00e9 des donn\u00e9es transmises en lignes sont mis en \u0153uvre par Jam\u00f3n App\u00e9tit. En cas de paiement par carte bleue, la transaction s\u2019effectue via une banque de renom (Banco Santander) qui seule dispose des informations bancaires fournies sur le site au moment du paiement.<\/p>\n<p><strong>Pr\u00e9paration de commande<\/strong><\/p>\n<p>La commande est pr\u00e9par\u00e9e lorsque Jam\u00f3n App\u00e9tit encaiss\u00e9 l\u2019int\u00e9gralit\u00e9 du r\u00e8glement, et que tous les \u00e9l\u00e9ments n\u00e9cessaires \u00e0 la bonne ex\u00e9cution de l\u2019envoi sont exploitables soit\u00a0:<\/p>\n<p>Adresse exacte de facturation, nom du contact et coordonn\u00e9es t\u00e9l\u00e9phoniques\u00a0\u2013 Code Porte, \u00e9tage etc.<\/p>\n<p>Adresse exacte de livraison et coordonn\u00e9es t\u00e9l\u00e9phoniques des destinataires.<\/p>\n<p>Si le colis ne peut \u00eatre livr\u00e9 du fait d\u2019une adresse de livraison incorrecte ou incompl\u00e8te, il sera retourn\u00e9 \u00e0 Jam\u00f3n App\u00e9tit. La re-livraison se fera moyennant facturation de frais de port suppl\u00e9mentaires.<\/p>\n<p><strong>Livraison<\/strong><\/p>\n<p><strong>D\u00e9lai de livraison et mode de r\u00e8glement<\/strong><\/p>\n<p>Votre commande pass\u00e9e sur le site www.jamonappetit.com est valid\u00e9e d\u00e8s que la soci\u00e9t\u00e9 Jam\u00f3n App\u00e9tit re\u00e7oit confirmation de votre r\u00e8glement.<\/p>\n<p>Le montant des frais de livraison est indiqu\u00e9 au debut de votre commande.<\/p>\n<p>Votre commande vous sera d\u00e9livr\u00e9e \u00e0 l\u2019adresse indiqu\u00e9e dans la zone \u00ab\u00a0Adresse de livraison\u00a0\u00bb que vous compl\u00e9tez d\u00e8s la validation de votre panier.<\/p>\n<p>La soci\u00e9t\u00e9 Jam\u00f3n App\u00e9tit s\u2019engage \u00e0 tout mettre en \u0153uvre afin de vous assurer l&rsquo;exp\u00e9dition de votre commande dans les meilleurs d\u00e9lais apr\u00e8s sa confirmation et la validation du paiement, soit dans un d\u00e9lai de 2 \u00e0 3 jours ouvr\u00e9s maximum apr\u00e8s passage de la commande et paiement complet.<\/p>\n<p>Nous attirons votre attention sur le fait que les d\u00e9lais de livraison ci-dessus sont applicables hors probl\u00e8me d\u2019acheminement postal ou de force majeure et selon disponibilit\u00e9 des produits.<\/p>\n<p>Le jour de l\u2019exp\u00e9dition de votre commande, un email vous sera envoy\u00e9 vous informant de l\u2019exp\u00e9dition, et pr\u00e9cisant le N\u00b0 du colis, ainsi que l\u2019adresse web du transporteur afin de pouvoir suivre l\u2019acheminement du colis.<\/p>\n<p>Dans l\u2019\u00e9ventualit\u00e9 d\u2019un retard dans le d\u00e9lai de livraison, Jam\u00f3n App\u00e9tit pourra s\u2019exon\u00e9rer de tout ou partie de sa responsabilit\u00e9 en apportant la preuve que l\u2019inex\u00e9cution ou la mauvaise ex\u00e9cution du contrat est imputable, soit au consommateur, soit au fait, impr\u00e9visible et insurmontable, d\u2019un tiers au contrat, soit \u00e0 un cas de force majeure.<\/p>\n<p>Les produits demeurent la propri\u00e9t\u00e9 de Jam\u00f3n App\u00e9tit jusqu\u2019au complet paiement du prix.<\/p>\n<p><strong>Disponibilit\u00e9<\/strong><\/p>\n<p>Toute commande sera honor\u00e9e dans la limite des stocks disponibles. En cas d\u2019indisponibilit\u00e9 des produits apr\u00e8s passation de votre commande, nous nous engageons \u00e0 vous en informer par e-mail ou t\u00e9l\u00e9phone dans les plus brefs d\u00e9lais. Vous pourrez alors demander l\u2019annulation de tout ou partie de votre commande ou l\u2018\u00e9change du ou des produits concern\u00e9s.<\/p>\n<p><strong>Zone et conditions de livraison<\/strong><\/p>\n<p>La soci\u00e9t\u00e9 Jam\u00f3n App\u00e9tit organise la livraison des produits command\u00e9s sur le site www.jamonappetit.com dans tous les pays desservis par la Poste ou ses partenaires locaux.<\/p>\n<p>Les \u00e9ventuels droits de douane, taxes, redevances ou impositions diverses sont \u00e0 la charge du destinataire.<br \/>\nLes montants de ces taxes d\u00e9pendent de la r\u00e8glementation en\u00a0vigueur dans chaque pays de destination.<br \/>\nJam\u00f3n App\u00e9tit n\u2019a aucun contr\u00f4le sur ces taxes et ne peut pr\u00e9voir leur montant.<br \/>\nEn fonction des diff\u00e9rentes r\u00e8glementations douani\u00e8res de chaque pays, il appartient au client de s\u2019informer aupr\u00e8s des autorit\u00e9s locales concern\u00e9es des \u00e9ventuelles limitations d\u2019importation sur le territoire\u00a0du pays de destination des produits qu\u2019il d\u00e9sire commander. Il appartient au client de v\u00e9rifier pr\u00e9alablement, et sous sa seule responsabilit\u00e9, que l\u2019importation et la consommation de ces produits est bien conforme aux lois en vigueur du pays de destination<\/p>\n<p><strong>Mode de livraison.<\/strong><\/p>\n<p>Les exp\u00e9ditions de vos commandes, \u00e0 destination de la France m\u00e9tropolitaine et Belgique (livraison le\u00a0jour ouvr\u00e9 suivant l&rsquo;exp\u00e9dition,\u00a0avant 13h)\u00a0du Lundi au Jeudi.<\/p>\n<p><strong>Ev\u00e9nements exceptionnels et force majeure<\/strong><\/p>\n<p>En cas de gr\u00e8ve des services de La Poste, ou tout autre \u00e9v\u00e9nement de nature exceptionnelle ralentissant ou emp\u00eachant la livraison des colis (temp\u00eate de neige, attentats, guerres \u2026), Jam\u00f3n App\u00e9tit mettra tous les moyens en \u0153uvre pour informer le client de l&rsquo;\u00e9tat de l&rsquo;exp\u00e9dition de son colis, mais ne pourra \u00eatre tenue pour responsable des retards occasionn\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9ambule Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente sont conclues entre Jamon Appetit et toute personne effectuant un achat en ligne&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3973","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/jamonappetit.com\/fr\/wp-json\/wp\/v2\/pages\/3973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jamonappetit.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jamonappetit.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jamonappetit.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jamonappetit.com\/fr\/wp-json\/wp\/v2\/comments?post=3973"}],"version-history":[{"count":0,"href":"https:\/\/jamonappetit.com\/fr\/wp-json\/wp\/v2\/pages\/3973\/revisions"}],"wp:attachment":[{"href":"https:\/\/jamonappetit.com\/fr\/wp-json\/wp\/v2\/media?parent=3973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}